{"id":3821,"date":"2021-08-14T23:45:06","date_gmt":"2021-08-14T21:45:06","guid":{"rendered":"https:\/\/www.ofkbrdo.com\/Wordpress\/?p=3821"},"modified":"2021-08-14T23:45:06","modified_gmt":"2021-08-14T21:45:06","slug":"ofk-brdo-ide-u-nove-pobjede-2","status":"publish","type":"post","link":"https:\/\/www.ofkbrdo.com\/Wordpress\/ofk-brdo-ide-u-nove-pobjede-2\/","title":{"rendered":"OFK BRDO IDE U NOVE POBJEDE"},"content":{"rendered":"<p>Treba biti ponosan na klub koji \u017eivot zna\u010di. Svima vama koji ste na bilo koji na\u010din doprinijeli da Omladinski fudbalski klub Brdo postoji, jako smo zahvalni. Sigurni smo da nas dobro razumijete kada ka\u017eemo da je velika pobjeda postojanje kluba.<\/p>\n<p><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" data-attachment-id=\"3822\" data-permalink=\"https:\/\/www.ofkbrdo.com\/Wordpress\/ofk-brdo-ide-u-nove-pobjede-2\/trening\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening-scaled.jpg?fit=2560%2C1920&amp;ssl=1\" data-orig-size=\"2560,1920\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Trening\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening-scaled.jpg?fit=640%2C480&amp;ssl=1\" class=\"aligncenter size-large wp-image-3822\" src=\"https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening.jpg?resize=640%2C480&#038;ssl=1\" alt=\"\" width=\"640\" height=\"480\" srcset=\"https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening-scaled.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening-scaled.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening-scaled.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening-scaled.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening-scaled.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening-scaled.jpg?resize=310%2C233&amp;ssl=1 310w, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening-scaled.jpg?resize=60%2C45&amp;ssl=1 60w, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening-scaled.jpg?resize=640%2C480&amp;ssl=1 640w, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening-scaled.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening-scaled.jpg?w=1920&amp;ssl=1 1920w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>Zato smo jako ponosni \u0161to radimo u klubu koji je u tre\u0107em rangu takmi\u010denja na nivo BiH. I daleko ve\u0107e lokalne zajednice mogu nam pozavidjeti jer Brdo kre\u0107e u drugu drugoliga\u0161ki sezonu.<\/p>\n<p>Mnogo je izazova i bi\u0107e potrebno mnogo rada kako na treninzima i utakmicama, tako i izvan terena. Ma koliko \u010dlanova bilo u upravi, skup\u0161tini i drugim organima kluba, trebamo biti jedno bi\u0107e.<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"3823\" data-permalink=\"https:\/\/www.ofkbrdo.com\/Wordpress\/ofk-brdo-ide-u-nove-pobjede-2\/trening2\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening2-scaled.jpg?fit=2560%2C1920&amp;ssl=1\" data-orig-size=\"2560,1920\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Trening2\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening2-scaled.jpg?fit=640%2C480&amp;ssl=1\" class=\"aligncenter size-large wp-image-3823\" src=\"https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening2.jpg?resize=640%2C480&#038;ssl=1\" alt=\"\" width=\"640\" height=\"480\" srcset=\"https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening2-scaled.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening2-scaled.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening2-scaled.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening2-scaled.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening2-scaled.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening2-scaled.jpg?resize=310%2C233&amp;ssl=1 310w, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening2-scaled.jpg?resize=60%2C45&amp;ssl=1 60w, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening2-scaled.jpg?resize=640%2C480&amp;ssl=1 640w, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening2-scaled.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening2-scaled.jpg?w=1920&amp;ssl=1 1920w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>Hvala Bogu, dobro nam ide. Klub je stabilan i imamo tendenciju razvoja. Seniori, juniori i pioniri imaju mnogo obaveza i pred nama je da im osiguramo uslove za takmi\u010denje.<\/p>\n<p>Razloga za optimizam imamo dovoljno i vjerujemo u momke Mirze Alki\u0107a. Pred nama je nedjeljni ogled i prva ovosezonska utakmica u \u010celincu i veoma te\u017eak protivnik. Brdo je bez kapitena Karupovi\u0107a zbog \u017eutih kartona, a izostat \u0107e jo\u0161 nekoliko fudbalera. Me\u0111utim, bez obzira na sastav, svi igra\u010di moraju dati maksimum jer to zaslu\u017euje klub koji \u017eivot zna\u010di.<\/p>\n<p><img data-recalc-dims=\"1\" decoding=\"async\" data-attachment-id=\"3824\" data-permalink=\"https:\/\/www.ofkbrdo.com\/Wordpress\/ofk-brdo-ide-u-nove-pobjede-2\/trening3\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening3-scaled.jpg?fit=2560%2C1920&amp;ssl=1\" data-orig-size=\"2560,1920\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Trening3\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening3-scaled.jpg?fit=640%2C480&amp;ssl=1\" class=\"aligncenter size-large wp-image-3824\" src=\"https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening3.jpg?resize=640%2C480&#038;ssl=1\" alt=\"\" width=\"640\" height=\"480\" srcset=\"https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening3-scaled.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening3-scaled.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening3-scaled.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening3-scaled.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening3-scaled.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening3-scaled.jpg?resize=310%2C233&amp;ssl=1 310w, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening3-scaled.jpg?resize=60%2C45&amp;ssl=1 60w, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening3-scaled.jpg?resize=640%2C480&amp;ssl=1 640w, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening3-scaled.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening3-scaled.jpg?w=1920&amp;ssl=1 1920w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>Fudbalerima i stru\u010dnom \u0161tabu mnogo uspjeha i dosta bodova. Znajte da je iza vas veliki broj navija\u010da, \u010dlanova, sponzora, donatora i da mnogi najavljuju da \u0107e nam se pridru\u017ei.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Treba biti ponosan na klub koji \u017eivot zna\u010di. Svima vama koji ste na bilo koji na\u010din doprinijeli da Omladinski fudbalski klub Brdo postoji, jako smo zahvalni. Sigurni smo da nas dobro razumijete kada ka\u017eemo da je velika pobjeda postojanje kluba. Zato smo jako ponosni \u0161to radimo u klubu koji je u tre\u0107em rangu takmi\u010denja na [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3822,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1,12],"tags":[],"class_list":["post-3821","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vijesti","category-prva-ekipa"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/08\/Trening-scaled.jpg?fit=2560%2C1920&ssl=1","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pevKtx-ZD","jetpack-related-posts":[{"id":3979,"url":"https:\/\/www.ofkbrdo.com\/Wordpress\/slozna-braca-brdo-grade\/","url_meta":{"origin":3821,"position":0},"title":"SLO\u017dNA BRA\u0106A BRDO GRADE","author":"admin","date":"9. September 2021","format":false,"excerpt":"Po\u0161tovani prijatelji Omladinskog fudbalskog kluba Brdo, \u0161aljemo vam prijatne informacije iz rodnog kraja. Milion puta smo ponovili da \u017eelimo svima pokazati kako se voli i po\u0161tuje klub koji \u017eivot zna\u010di na transparentan i bpo\u0161ten na\u010din. Kao \u0161to znate ovog ljeta smo otvorili vrata klupskog kafi\u0107a. Smatramo da je za po\u010detak\u2026","rel":"","context":"In &quot;Razno&quot;","block_context":{"text":"Razno","link":"https:\/\/www.ofkbrdo.com\/Wordpress\/razno\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/09\/AB97149A-B09A-468B-AE91-A5C353D5B246.png?fit=1034%2C812&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/09\/AB97149A-B09A-468B-AE91-A5C353D5B246.png?fit=1034%2C812&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/09\/AB97149A-B09A-468B-AE91-A5C353D5B246.png?fit=1034%2C812&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/09\/AB97149A-B09A-468B-AE91-A5C353D5B246.png?fit=1034%2C812&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2902,"url":"https:\/\/www.ofkbrdo.com\/Wordpress\/odlican-odziv-na-pocetku-projekta-clanska-karta-za-buducnost-brda\/","url_meta":{"origin":3821,"position":1},"title":"ODLI\u010cAN ODZIV NA PO\u010cETKU PROJEKTA &#8211; &#8220;\u010cLANSKA KARTA ZA BUDU\u0106NOST BRDA&#8221;","author":"admin","date":"1. February 2021","format":false,"excerpt":"Ako se po jutru dan poznaje onda mo\u017eemo biti jako zadovoljni po\u010detkom, izuzetno va\u017enog projekta za Omladinski fudbalski klub Brdo. Ve\u0107 imamo 30 \u010dlanova, a na samom samom smo po\u010detku. Dobro smo se organizivali, u Evropi i preko okeana imamo ljude koji su dio ove pri\u010de. \u010clanska karta je zavr\u0161ila\u2026","rel":"","context":"In &quot;Pocetna&quot;","block_context":{"text":"Pocetna","link":"https:\/\/www.ofkbrdo.com\/Wordpress\/vijesti\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/02\/Duratovici.jpg?fit=750%2C461&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/02\/Duratovici.jpg?fit=750%2C461&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/02\/Duratovici.jpg?fit=750%2C461&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/02\/Duratovici.jpg?fit=750%2C461&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":7524,"url":"https:\/\/www.ofkbrdo.com\/Wordpress\/tri-velika-prijatelja-kluba-koji-zivot-znaci-i-mataruskog-brda\/","url_meta":{"origin":3821,"position":2},"title":"TRI VELIKA PRIJATELJA KLUBA KOJI \u017dIVOT ZNA\u010cI I MATARU\u0160KOG BRDA","author":"admin","date":"6. February 2024","format":false,"excerpt":"Od velike je va\u017enosti poja\u010dati konkurenciju u ekipi Omladinskog fudbalskog kluba Brdo. Dolazi proljetni dio prvenstva i valja se \u0161to bolje pripremiti i organizovati kako bi i dalje bili ambasadori Mataru\u0161kog Brda. Koliko je va\u017ena ekipa koja nastupa, toliko je va\u017ena ekipa sjajnih ljudi koja se okupila oko kluba koji\u2026","rel":"","context":"In &quot;Sponzori&quot;","block_context":{"text":"Sponzori","link":"https:\/\/www.ofkbrdo.com\/Wordpress\/sponzori\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2024\/02\/IMG_5910.jpeg?fit=1198%2C481&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2024\/02\/IMG_5910.jpeg?fit=1198%2C481&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2024\/02\/IMG_5910.jpeg?fit=1198%2C481&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2024\/02\/IMG_5910.jpeg?fit=1198%2C481&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2024\/02\/IMG_5910.jpeg?fit=1198%2C481&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":9684,"url":"https:\/\/www.ofkbrdo.com\/Wordpress\/hvala-vam-sto-ste-uljepsali-zuto-plavu-noc\/","url_meta":{"origin":3821,"position":3},"title":"HVALA VAM \u0160TO STE ULJEP\u0160ALI \u017dUTO PLAVU NO\u0106","author":"admin","date":"29. December 2025","format":false,"excerpt":"Da, bila je to predivna no\u0107 u kojoj smo pokazali da nam Omladinski fudbalski klub Brdo mnogo zna\u010di. Odli\u010dno raspolo\u017eenje uz Esada Plavog, majstora svog zanata, potrajalo je do sitnih sati. Jako nas raduje \u0161to smo me\u0111u gostima imali i dosta mlade raje od koje se o\u010dekuje da narednih godina\u2026","rel":"","context":"In &quot;Dru\u017eenje&quot;","block_context":{"text":"Dru\u017eenje","link":"https:\/\/www.ofkbrdo.com\/Wordpress\/druzenje\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2025\/12\/IMG_7019.jpeg?fit=1200%2C540&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2025\/12\/IMG_7019.jpeg?fit=1200%2C540&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2025\/12\/IMG_7019.jpeg?fit=1200%2C540&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2025\/12\/IMG_7019.jpeg?fit=1200%2C540&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2025\/12\/IMG_7019.jpeg?fit=1200%2C540&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":4696,"url":"https:\/\/www.ofkbrdo.com\/Wordpress\/ofk-brdo-kohezioni-faktor-u-lokalnoj-zajednici\/","url_meta":{"origin":3821,"position":4},"title":"OFK BRDO KOHEZIONI FAKTOR U LOKALNOJ ZAJEDNICI","author":"admin","date":"27. December 2021","format":false,"excerpt":"Bilo je to nezaboravno ve\u010de koje smo poklonili Omladinskom fudbalskom klubu Brdo. Uprava kluba je ozbiljno shvatila svoje obaveze i pripremila dodatne stolove i stolice za na\u0161e prijatelje, ro\u0111ake, kom\u0161ije, poznanike,... koji su u maksimalnom kapacitetu ispunili Dru\u0161tveni dom Hambarine. Da li smo o\u010dekivali ovako impozantan skup? Jesmo i nismo\u2026","rel":"","context":"In &quot;Dru\u017eenje&quot;","block_context":{"text":"Dru\u017eenje","link":"https:\/\/www.ofkbrdo.com\/Wordpress\/druzenje\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/12\/EDFCE2DD-9772-4528-B869-8B01ED154D33.jpeg?fit=1200%2C594&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/12\/EDFCE2DD-9772-4528-B869-8B01ED154D33.jpeg?fit=1200%2C594&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/12\/EDFCE2DD-9772-4528-B869-8B01ED154D33.jpeg?fit=1200%2C594&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/12\/EDFCE2DD-9772-4528-B869-8B01ED154D33.jpeg?fit=1200%2C594&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2021\/12\/EDFCE2DD-9772-4528-B869-8B01ED154D33.jpeg?fit=1200%2C594&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":5587,"url":"https:\/\/www.ofkbrdo.com\/Wordpress\/transparentan-rad-omladinskog-fudbalskog-kluba-brdo\/","url_meta":{"origin":3821,"position":5},"title":"TRANSPARENTAN RAD OMLADINSKOG FUDBALSKOG KLUBA BRDO","author":"admin","date":"3. August 2022","format":false,"excerpt":"Delegati Skup\u0161tine Omladinskog fudbalskog kluba Brdo jednoglasno su konstovali da je u proteklom periodu ostvaren zna\u010dajan napredak na rezultatskom i organizacionom planu. Jednoglasno je nakon razmatranja usvojen finansijski izvje\u0161taj \u0161to potvr\u0111uje da je se u izvje\u0161tajnom periodu doma\u0107inski odnosilo prema raspolo\u017eivim finansijskim sredstvima. U tom pogledu treba pohvaliti rad klupskih\u2026","rel":"","context":"In &quot;Razno&quot;","block_context":{"text":"Razno","link":"https:\/\/www.ofkbrdo.com\/Wordpress\/razno\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2022\/08\/4F700E37-E46F-411A-BAB7-551971DE2A7C-scaled.jpeg?fit=1200%2C854&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2022\/08\/4F700E37-E46F-411A-BAB7-551971DE2A7C-scaled.jpeg?fit=1200%2C854&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2022\/08\/4F700E37-E46F-411A-BAB7-551971DE2A7C-scaled.jpeg?fit=1200%2C854&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2022\/08\/4F700E37-E46F-411A-BAB7-551971DE2A7C-scaled.jpeg?fit=1200%2C854&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/www.ofkbrdo.com\/Wordpress\/wp-content\/uploads\/2022\/08\/4F700E37-E46F-411A-BAB7-551971DE2A7C-scaled.jpeg?fit=1200%2C854&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.ofkbrdo.com\/Wordpress\/wp-json\/wp\/v2\/posts\/3821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ofkbrdo.com\/Wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ofkbrdo.com\/Wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ofkbrdo.com\/Wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ofkbrdo.com\/Wordpress\/wp-json\/wp\/v2\/comments?post=3821"}],"version-history":[{"count":0,"href":"https:\/\/www.ofkbrdo.com\/Wordpress\/wp-json\/wp\/v2\/posts\/3821\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ofkbrdo.com\/Wordpress\/wp-json\/wp\/v2\/media\/3822"}],"wp:attachment":[{"href":"https:\/\/www.ofkbrdo.com\/Wordpress\/wp-json\/wp\/v2\/media?parent=3821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ofkbrdo.com\/Wordpress\/wp-json\/wp\/v2\/categories?post=3821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ofkbrdo.com\/Wordpress\/wp-json\/wp\/v2\/tags?post=3821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}